{"id":227,"date":"2014-05-04T20:37:18","date_gmt":"2014-05-04T18:37:18","guid":{"rendered":"http:\/\/auderghem.ecolo.me\/2014\/05\/04\/conseil-communal-du-30-avril-2014\/"},"modified":"2014-05-04T20:37:18","modified_gmt":"2014-05-04T18:37:18","slug":"conseil-communal-du-30-avril-2014","status":"publish","type":"post","link":"https:\/\/auderghem.ecolo.be\/nl\/2014\/05\/04\/conseil-communal-du-30-avril-2014\/","title":{"rendered":"Conseil communal du 30 avril 2014"},"content":{"rendered":"<p><strong>Interpellation du groupe Ecolo-Groen sur la vente du b\u00e2timent La Grande<br \/>\nLani\u00e8re au Gets<\/strong><\/p>\n<p>Lors du conseil communal du 19 d\u00e9cembre 2013, vous avez d\u00e9cid\u00e9 de mettre en vente le b\u00e2timent La Grande Lani\u00e8re aux Gets en arguant du co\u00fbt \u00e9lev\u00e9 d&#8217;une r\u00e9novation lourde impos\u00e9e par une nouvelle l\u00e9gislation fran\u00e7aise.<\/p>\n<p>Vous n&#8217;\u00eates pas sans ignorer que le gouvernement fran\u00e7ais \u00e0 postposer, fin f\u00e9vrier 2014, l&#8217;application de cette loi, non plus au 1er janvier 2015 mais bien au 1er janvier 2021.<\/p>\n<p>La vente du domaine ne s&#8217;impose donc plus comme vous l&#8217;aviez pr\u00e9sent\u00e9 au Conseil. Nous avions d&#8217;ailleurs indiqu\u00e9 lors de ce m\u00eame Conseil qu&#8217;il y aurait probablement des mesures d&#8217;am\u00e9nagement et qu&#8217;il n&#8217;y avait pas d&#8217;urgence.<\/p>\n<p>Nous demandons au Coll\u00e8ge :<br \/>\n<br \/>&nbsp;O\u00f9 en est la proc\u00e9dure d&#8217;appel \u00e0 la concurrence pour la vente du b\u00e2timent?<br \/>\n<br \/>&nbsp;Le coll\u00e8ge a-t\u2019il l\u2019intention de revenir sur la d\u00e9cision de vente du domaine compte tenu de l&#8217;exploitation encore possible sans grosse r\u00e9novation pendant les 6 prochaines ann\u00e9es<br \/>\n<br \/>&nbsp;Quelles sont les solutions alternatives qui sont actuellement pr\u00e9vues pour les classes de neige des \u00e9coles d&#8217;Auderghem de l&#8217;ann\u00e9e prochaine Nous vous remercions pour l\u2019attention que vous porterez \u00e0 notre interpellation.<\/p>\n<p>Vincent Molenberg<\/p>\n<p>Chef de groupe Ecolo-Groen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interpellation du groupe Ecolo-Groen sur la vente du b\u00e2timent La Grande Lani\u00e8re au Gets Lors du conseil communal du 19 d\u00e9cembre 2013, vous avez d\u00e9cid\u00e9 de mettre en vente le b\u00e2timent La Grande Lani\u00e8re aux Gets en arguant du co\u00fbt \u00e9lev\u00e9 d&#8217;une r\u00e9novation lourde impos\u00e9e par une nouvelle l\u00e9gislation fran\u00e7aise. Vous n&#8217;\u00eates pas sans ignorer &hellip;<\/p>\n","protected":false},"author":638,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[11],"tags":[13],"class_list":["post-227","post","type-post","status-publish","format-standard","hentry","category-legislature-2012-2018","tag-homepage-news-onoff"],"acf":[],"_links":{"self":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/posts\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/users\/638"}],"replies":[{"embeddable":true,"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/comments?post=227"}],"version-history":[{"count":0,"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/posts\/227\/revisions"}],"wp:attachment":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/media?parent=227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/categories?post=227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/tags?post=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}