{"id":12,"count":3,"description":"Contact : 1160ecolo@gmail.com","link":"https:\/\/auderghem.ecolo.be\/nl\/category\/nos-elus\/","name":"Nos \u00e9lus","slug":"nos-elus","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/auderghem.ecolo.be\/nl\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}